{"id":223541,"date":"2025-06-03T11:03:45","date_gmt":"2025-06-03T15:03:45","guid":{"rendered":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157.jpg"},"modified":"2025-06-03T11:11:48","modified_gmt":"2025-06-03T15:11:48","slug":"img_0157-2","status":"inherit","type":"attachment","link":"https:\/\/experiencescanada.bcdn.ca\/fr\/?attachment_id=223541","title":{"rendered":"IMG_0157"},"author":44,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-223541","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IMG_0157 - Experiences Canada<\/title>\n<meta name=\"description\" content=\"juin 3, 2025\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMG_0157 - Experiences Canada\" \/>\n<meta property=\"og:description\" content=\"juin 3, 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Experiences Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/experiences.canada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-03T15:11:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@experiencescan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/experiencescanada.bcdn.ca\\\/wp-content\\\/uploads\\\/IMG_0157-scaled-e1748963134996.jpg\",\"url\":\"https:\\\/\\\/experiencescanada.bcdn.ca\\\/wp-content\\\/uploads\\\/IMG_0157-scaled-e1748963134996.jpg\",\"name\":\"IMG_0157 - Experiences Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/experiencescanada.bcdn.ca\\\/#website\"},\"datePublished\":\"2025-06-03T15:03:45+00:00\",\"dateModified\":\"2025-06-03T15:11:48+00:00\",\"description\":\"juin 3, 2025\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/experiencescanada.bcdn.ca\\\/wp-content\\\/uploads\\\/IMG_0157-scaled-e1748963134996.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/experiencescanada.bcdn.ca\\\/wp-content\\\/uploads\\\/IMG_0157-scaled-e1748963134996.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/experiencescanada.bcdn.ca\\\/wp-content\\\/uploads\\\/IMG_0157-scaled-e1748963134996.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/experiencescanada.bcdn.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IMG_0157\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/experiencescanada.bcdn.ca\\\/#website\",\"url\":\"https:\\\/\\\/experiencescanada.bcdn.ca\\\/\",\"name\":\"Experiences Canada\",\"description\":\"See More, Be More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/experiencescanada.bcdn.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMG_0157 - Experiences Canada","description":"juin 3, 2025","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"IMG_0157 - Experiences Canada","og_description":"juin 3, 2025","og_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg","og_site_name":"Experiences Canada","article_publisher":"https:\/\/www.facebook.com\/experiences.canada\/","article_modified_time":"2025-06-03T15:11:48+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@experiencescan","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg","url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg","name":"IMG_0157 - Experiences Canada","isPartOf":{"@id":"https:\/\/experiencescanada.bcdn.ca\/#website"},"datePublished":"2025-06-03T15:03:45+00:00","dateModified":"2025-06-03T15:11:48+00:00","description":"juin 3, 2025","breadcrumb":{"@id":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/experiencescanada.bcdn.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"IMG_0157"}]},{"@type":"WebSite","@id":"https:\/\/experiencescanada.bcdn.ca\/#website","url":"https:\/\/experiencescanada.bcdn.ca\/","name":"Experiences Canada","description":"See More, Be More","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experiencescanada.bcdn.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":2560,"file":"IMG_0157-scaled.jpg","filesize":779632,"sizes":{"medium_large":{"file":"IMG_0157-768x1024.jpg","width":768,"height":1024,"filesize":119742,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-768x1024.jpg"},"1536x1536":{"file":"IMG_0157-1152x1536.jpg","width":1152,"height":1536,"filesize":273446,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-1152x1536.jpg"},"2048x2048":{"file":"IMG_0157-1536x2048.jpg","width":1536,"height":2048,"filesize":496777,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-1536x2048.jpg"},"et-pb-post-main-image":{"file":"IMG_0157-400x250.jpg","width":400,"height":250,"filesize":24603,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-400x250.jpg"},"et-pb-post-main-image-fullwidth":{"file":"IMG_0157-1080x675.jpg","width":1080,"height":675,"filesize":121692,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-1080x675.jpg"},"et-pb-portfolio-image":{"file":"IMG_0157-400x284.jpg","width":400,"height":284,"filesize":26086,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-400x284.jpg"},"et-pb-portfolio-module-image":{"file":"IMG_0157-510x382.jpg","width":510,"height":382,"filesize":37342,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-510x382.jpg"},"et-pb-portfolio-image-single":{"file":"IMG_0157-1080x1440.jpg","width":1080,"height":1440,"filesize":239108,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-1080x1440.jpg"},"et-pb-gallery-module-image-portrait":{"file":"IMG_0157-400x516.jpg","width":400,"height":516,"filesize":37657,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-400x516.jpg"},"et-pb-post-main-image-fullwidth-large":{"file":"IMG_0157-2880x1800.jpg","width":2880,"height":1800,"filesize":806394,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-2880x1800.jpg"},"et-pb-image--responsive--desktop":{"file":"IMG_0157-1280x1707.jpg","width":1280,"height":1707,"filesize":341465,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-1280x1707.jpg"},"et-pb-image--responsive--tablet":{"file":"IMG_0157-980x1307.jpg","width":980,"height":1307,"filesize":197202,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-980x1307.jpg"},"et-pb-image--responsive--phone":{"file":"IMG_0157-480x640.jpg","width":480,"height":640,"filesize":51299,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-480x640.jpg"},"awsm_team":{"file":"IMG_0157-500x500.jpg","width":500,"height":500,"filesize":44173,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-500x500.jpg"},"full":{"file":"IMG_0157-scaled-e1748963134996.jpg","width":1920,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]},"original_image":"IMG_0157.jpg"},"post":223539,"source_url":"https:\/\/experiencescanada.bcdn.ca\/wp-content\/uploads\/IMG_0157-scaled-e1748963134996.jpg","_links":{"self":[{"href":"https:\/\/experiencescanada.bcdn.ca\/fr\/wp-json\/wp\/v2\/media\/223541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/experiencescanada.bcdn.ca\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/experiencescanada.bcdn.ca\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/experiencescanada.bcdn.ca\/fr\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/experiencescanada.bcdn.ca\/fr\/wp-json\/wp\/v2\/comments?post=223541"}],"wp:attached-to":[{"embeddable":true,"post_type":"awsm_team_member","id":223539,"href":"https:\/\/experiencescanada.bcdn.ca\/fr\/wp-json\/wp\/v2\/awsm_team_member\/223539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}